{"id":25164,"date":"2025-05-14T16:49:06","date_gmt":"2025-05-14T15:49:06","guid":{"rendered":"https:\/\/idealpesca.com\/loja\/produto\/carreto-daiwa-legalis-20-lt-4000-cxh\/"},"modified":"2026-05-15T19:43:24","modified_gmt":"2026-05-15T18:43:24","slug":"carreto-daiwa-legalis-20-lt-4000-cxh","status":"publish","type":"product","link":"https:\/\/idealpesca.com\/loja\/produto\/carreto-daiwa-legalis-20-lt-4000-cxh\/","title":{"rendered":"Carreto DAIWA LEGALIS 20 LT 4000 CXH"},"content":{"rendered":"<div class=\"product-desc\">\n<table class=\"table bordered js-pswp-gallery\">\n<thead>\n<tr>\n<th>\u00a0<\/th>\n<th>Refer\u00eancia<\/th>\n<th>Pega<\/th>\n<th>R\u00e1cio (\/1)<\/th>\n<th>VMV<\/th>\n<th>Peso<\/th>\n<th>Nylon<\/th>\n<th>Multifilamento<\/th>\n<th>Drag<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><span class=\"new\">N<\/span><\/td>\n<td><a class=\"picture js-pswp-item\" href=\"https:\/\/www.daiwa.pt\/uploads\/products\/reels\/2020\/10\/leg20lt4000cxh_1200x1200.jpg\" data-size=\"1200x1200\" data-med=\"\/uploads\/products\/reels\/2020\/10\/leg20lt4000cxh_800x800.jpg\" data-med-size=\"800x800\"> <span class=\"inner\"> <img loading=\"lazy\" decoding=\"async\" src=\"image\/gif;base64,R0lGODlhAQABAIAAAMLCwgAAACH5BAAAAAAALAAAAAABAAEAAAICRAEAOw==\" alt=\"\" width=\"1\" height=\"1\" \/><\/span><\/a><\/p>\n<figure>LEG20LT4000CXH<\/figure>\n<\/td>\n<td>T<\/td>\n<td>6,2<\/td>\n<td>99cm<\/td>\n<td>235g<\/td>\n<td>0.28mm-150m<\/td>\n<td>0.18mm-200m<\/td>\n<td>12kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Os carretos Legalis apresentam uma gama completa de tamanhos 1000 a 6000. Equipados com o Air Rotor em forma de arco em carbono Zaion V, ainda mais s\u00f3lido disp\u00f5em de uma rota\u00e7\u00e3o fluida. O drag de \u00faltima gera\u00e7\u00e3o ATD torna poss\u00edvel dominar os combates desde o toque at\u00e9 \u00e0 coloca\u00e7\u00e3o em seco. O corpo compacto em carbono Zaion V e a robusta roda de coroa Tough Digigear fazem do Legalis LT 2020 um carreto com uma excecional rela\u00e7\u00e3o leveza-resist\u00eancia, tudo a um pre\u00e7o muito atraente!<\/p>\n<\/div>\n<ul class=\"product-specifications\">\n<li>Drag com tecnologia ATD, bot\u00e3o de drag grande formato<\/li>\n<li>Rolamentos : 5 + 1<\/li>\n<li>Corpo e rotor em carbono Zaion V<\/li>\n<li>Bobina Air Spool em alum\u00ednio<\/li>\n<li>Enrolamento por espiras cruzadas<\/li>\n<li>Manivela alum\u00ednio ultraleve rebat\u00edvel<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DAIWA LEGALIS EMBRAIAGEM POTENTE E LEVEZA<\/p>\n","protected":false},"featured_media":28004,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[45,74],"product_tag":[],"class_list":["post-25164","product","type-product","status-publish","has-post-thumbnail","product_cat-020200-boia-spinning-eging","product_cat-020203-daiwa","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/idealpesca.com\/loja\/wp-json\/wp\/v2\/product\/25164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idealpesca.com\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/idealpesca.com\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/idealpesca.com\/loja\/wp-json\/wp\/v2\/comments?post=25164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idealpesca.com\/loja\/wp-json\/wp\/v2\/media\/28004"}],"wp:attachment":[{"href":"https:\/\/idealpesca.com\/loja\/wp-json\/wp\/v2\/media?parent=25164"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/idealpesca.com\/loja\/wp-json\/wp\/v2\/product_brand?post=25164"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/idealpesca.com\/loja\/wp-json\/wp\/v2\/product_cat?post=25164"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/idealpesca.com\/loja\/wp-json\/wp\/v2\/product_tag?post=25164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}